{"id":6216,"date":"2021-01-06T11:29:31","date_gmt":"2021-01-06T11:29:31","guid":{"rendered":"http:\/\/cortado-website.local\/?post_type=case-study&#038;p=6216"},"modified":"2025-08-14T14:01:41","modified_gmt":"2025-08-14T14:01:41","slug":"pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen","status":"publish","type":"case-study","link":"https:\/\/www.cortado.com\/de\/fallstudie\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\/","title":{"rendered":"Gute Pflege &amp; Wundversorgung &#8211; verbunden mit digitalen Arbeitsabl\u00e4ufen"},"content":{"rendered":"<h3>Informieren, dokumentieren, zum Pflegebed\u00fcrftigen navigieren: Gemietete Smartphones und Tablets von fonlos, verwaltet mit Cortado MDM, optimieren die Arbeitsabl\u00e4ufe bei Aurelia Pflegedienst und Wundversorgung<\/h3>\n<p>Aurelia und Erkan Erul erf\u00fcllten sich 2019 einen beruflichen Traum und er\u00f6ffneten den <a href=\"https:\/\/www.aurelia-pflegedienst.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">Aurelia Pflegedienst &amp; Wundversorgung<\/a><span>. Mit Erfolg! Mittlerweile besch\u00e4ftigt das Unternehmen im nieders\u00e4chsischen Seelze 16 Mitarbeiterinnen und Mitarbeiter, die Pflegebed\u00fcrftige versorgen. Erkan Erul kannte sich bereits vor der Gr\u00fcndung seines Pflegedienstes sehr gut mit IT aus. F\u00fcr seine Frau und ihn war klar, dass sie ihre Mitarbeiter mit Smartphones ausstatten wollten.<\/span><\/p>\n<p>Verwaltet werden die Ger\u00e4te und die Apps mit Cortado MDM. Kein Smartphone k\u00f6nne bei pflegerischen T\u00e4tigkeiten helfen, so der Gesch\u00e4ftsf\u00fchrer des Pflegedienstes. Erkan Erul: \u201eWo Technik als eine Entlastung der Arbeit fungiert, ist im\u00a0Informationstausch.\u201c Durch den schnelleren Austausch zwischen den Pflegenden und der Pflegedienstleitung k\u00f6nne man schneller auf Gegebenheiten reagieren, und das sei nat\u00fcrlich ein Qualit\u00e4tsmerkmal.<\/p>\n<p>Und auch im Bereich der Dokumentation\u00a0sorgen die Smartphones f\u00fcr mehr Effizienz. Eine branchen\u00fcbliche Pflegesoftware zeigt den Mitarbeitern den Tourenplan an. Herr Erul: \u201eSie k\u00f6nnen also damit\u00a0navigieren, Informationen \u00fcber den zu Pflegenden dokumentieren, neue Leistungen hinzuf\u00fcgen und sogar die\u00a0Arbeitszeiten erfassen.\u201c Wird der Tourenplan ver\u00e4ndert, bekommt das Pflegepersonal eine Push-Nachricht aufs Smartphone.<\/p>\n<p>Bei der Wundversorgung setzt der Pflegedienst auf Tablets. Musste man Wunden fr\u00fcher mit dem Lineal ausmessen und der Krankenkasse ein Foto schicken, arbeitet das Personal heute mit einer Software mit integriertem digitalen Lineal.<\/p>\n<p>Mit den Ger\u00e4ten werden au\u00dferdem Patientendokumente gescannt und direkt an das Krankenhaus weitergeleitet.<\/p>\n<p>Herr Erul ist zufrieden.<\/p>\n<blockquote><p>Man erspart sich wahnsinnig viel Zeit! Die Bedienung der Ger\u00e4te und der Cortado-Software ist einfach und selbsterkl\u00e4rend.<\/p><\/blockquote>\n<p>Einen pers\u00f6nlichen Vorteil habe er durch seine Vorkenntnisse im IT-Bereich. Er ist sich aber sicher, dass durch die einfache Bedienbarkeit jeder damit arbeiten k\u00f6nne.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informieren, dokumentieren, zum Pflegebed\u00fcrftigen navigieren: Gemietete Smartphones und Tablets von fonlos, verwaltet mit Cortado MDM, optimieren die Arbeitsabl\u00e4ufe bei Aurelia Pflegedienst und Wundversorgung.<\/p>\n","protected":false},"author":8,"featured_media":6661,"template":"","case-study-industry":[10975],"class_list":["post-6216","case-study","type-case-study","status-publish","has-post-thumbnail","hentry","case-study-industry-gesundheit-soziales"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.9 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Digitale Arbeitsabl\u00e4ufe in Pflege &amp; Wundversorgung \u2013 Case Study<\/title>\n<meta name=\"description\" content=\"Gemietete Smartphones und Tablets von fonlos, verwaltet mit Cortado MDM, optimieren die Arbeitsabl\u00e4ufe bei Aurelia Pflegedienst und Wundversorgung. \u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cortado.com\/de\/fallstudie\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gute Pflege &amp; Wundversorgung - verbunden mit digitalen Arbeitsabl\u00e4ufen\" \/>\n<meta property=\"og:description\" content=\"Gemietete Smartphones und Tablets von fonlos, verwaltet mit Cortado MDM, optimieren die Arbeitsabl\u00e4ufe bei Aurelia Pflegedienst und Wundversorgung. \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cortado.com\/de\/fallstudie\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\/\" \/>\n<meta property=\"og:site_name\" content=\"Cortado\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CortadoMobileSolutions\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-14T14:01:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cortado.com\/wp-content\/uploads\/Wundversorgung_Aurelia_Cortado-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cortado_com\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/fallstudie\\\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\\\/\",\"url\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/fallstudie\\\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\\\/\",\"name\":\"Digitale Arbeitsabl\u00e4ufe in Pflege & Wundversorgung \u2013 Case Study\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/fallstudie\\\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/fallstudie\\\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cortado.com\\\/wp-content\\\/uploads\\\/Wundversorgung_Aurelia_Cortado-scaled.jpg\",\"datePublished\":\"2021-01-06T11:29:31+00:00\",\"dateModified\":\"2025-08-14T14:01:41+00:00\",\"description\":\"Gemietete Smartphones und Tablets von fonlos, verwaltet mit Cortado MDM, optimieren die Arbeitsabl\u00e4ufe bei Aurelia Pflegedienst und Wundversorgung. \u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/fallstudie\\\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cortado.com\\\/de\\\/fallstudie\\\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/fallstudie\\\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cortado.com\\\/wp-content\\\/uploads\\\/Wundversorgung_Aurelia_Cortado-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cortado.com\\\/wp-content\\\/uploads\\\/Wundversorgung_Aurelia_Cortado-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Arzt klebt Gips auf ein Knie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/fallstudie\\\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fallstudien\",\"item\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/fallstudie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gute Pflege &amp; Wundversorgung &#8211; verbunden mit digitalen Arbeitsabl\u00e4ufen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/\",\"name\":\"Cortado\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Digitale Arbeitsabl\u00e4ufe in Pflege & Wundversorgung \u2013 Case Study","description":"Gemietete Smartphones und Tablets von fonlos, verwaltet mit Cortado MDM, optimieren die Arbeitsabl\u00e4ufe bei Aurelia Pflegedienst und Wundversorgung. \u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cortado.com\/de\/fallstudie\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\/","og_locale":"de_DE","og_type":"article","og_title":"Gute Pflege &amp; Wundversorgung - verbunden mit digitalen Arbeitsabl\u00e4ufen","og_description":"Gemietete Smartphones und Tablets von fonlos, verwaltet mit Cortado MDM, optimieren die Arbeitsabl\u00e4ufe bei Aurelia Pflegedienst und Wundversorgung. \u00a0","og_url":"https:\/\/www.cortado.com\/de\/fallstudie\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\/","og_site_name":"Cortado","article_publisher":"https:\/\/www.facebook.com\/CortadoMobileSolutions\/","article_modified_time":"2025-08-14T14:01:41+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.cortado.com\/wp-content\/uploads\/Wundversorgung_Aurelia_Cortado-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@cortado_com","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cortado.com\/de\/fallstudie\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\/","url":"https:\/\/www.cortado.com\/de\/fallstudie\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\/","name":"Digitale Arbeitsabl\u00e4ufe in Pflege & Wundversorgung \u2013 Case Study","isPartOf":{"@id":"https:\/\/www.cortado.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cortado.com\/de\/fallstudie\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\/#primaryimage"},"image":{"@id":"https:\/\/www.cortado.com\/de\/fallstudie\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cortado.com\/wp-content\/uploads\/Wundversorgung_Aurelia_Cortado-scaled.jpg","datePublished":"2021-01-06T11:29:31+00:00","dateModified":"2025-08-14T14:01:41+00:00","description":"Gemietete Smartphones und Tablets von fonlos, verwaltet mit Cortado MDM, optimieren die Arbeitsabl\u00e4ufe bei Aurelia Pflegedienst und Wundversorgung. \u00a0","breadcrumb":{"@id":"https:\/\/www.cortado.com\/de\/fallstudie\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cortado.com\/de\/fallstudie\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.cortado.com\/de\/fallstudie\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\/#primaryimage","url":"https:\/\/www.cortado.com\/wp-content\/uploads\/Wundversorgung_Aurelia_Cortado-scaled.jpg","contentUrl":"https:\/\/www.cortado.com\/wp-content\/uploads\/Wundversorgung_Aurelia_Cortado-scaled.jpg","width":2560,"height":1707,"caption":"Arzt klebt Gips auf ein Knie"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cortado.com\/de\/fallstudie\/pflege-und-wundversorgung-verbunden-mit-digitalen-arbeitsablaeufen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cortado.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Fallstudien","item":"https:\/\/www.cortado.com\/de\/fallstudie\/"},{"@type":"ListItem","position":3,"name":"Gute Pflege &amp; Wundversorgung &#8211; verbunden mit digitalen Arbeitsabl\u00e4ufen"}]},{"@type":"WebSite","@id":"https:\/\/www.cortado.com\/de\/#website","url":"https:\/\/www.cortado.com\/de\/","name":"Cortado","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cortado.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"}]}},"featured_img":"https:\/\/www.cortado.com\/wp-content\/uploads\/Wundversorgung_Aurelia_Cortado-scaled.jpg","coauthors":[],"author_meta":{"author_link":"https:\/\/www.cortado.com\/de\/author\/siklu\/","display_name":"Simone Fulton"},"relative_dates":{"created":"Ver\u00f6ffentlicht 6 Jahren vor","modified":"Aktualisiert 11 Monaten vor"},"absolute_dates":{"created":"Ver\u00f6ffentlicht am Januar 6, 2021","modified":"Aktualisiert am August 14, 2025"},"absolute_dates_time":{"created":"Ver\u00f6ffentlicht am Januar 6, 2021 11:29 am","modified":"Aktualisiert am August 14, 2025 2:01 pm"},"featured_img_caption":"","tax_additional":{"case-study-industry":{"linked":["<a href=\"https:\/\/www.cortado.com\/de\/fallstudie-branche\/gesundheit-soziales\/\" class=\"advgb-post-tax-term\">Gesundheit &amp; Soziales<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Gesundheit &amp; Soziales<\/span>"],"slug":"case-study-industry","name":"Branchen"}},"series_order":"","_links":{"self":[{"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/case-study\/6216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/case-study"}],"about":[{"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/types\/case-study"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/media\/6661"}],"wp:attachment":[{"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/media?parent=6216"}],"wp:term":[{"taxonomy":"case-study-industry","embeddable":true,"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/case-study-industry?post=6216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}