{"id":10042,"date":"2021-12-02T15:40:12","date_gmt":"2021-12-02T15:40:12","guid":{"rendered":"https:\/\/cortadoblog1.wpengine.com\/verbesserte-kennwortrichtlinien-android\/"},"modified":"2025-01-10T09:41:06","modified_gmt":"2025-01-10T09:41:06","slug":"verbesserte-kennwortrichtlinien-android","status":"publish","type":"post","link":"https:\/\/www.cortado.com\/de\/news\/verbesserte-kennwortrichtlinien-android\/","title":{"rendered":"Verbesserte Kennwortrichtlinien f\u00fcr Android-Ger\u00e4te"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"874\" height=\"658\" src=\"https:\/\/www.cortado.com\/wp-content\/uploads\/Bucket-Based-Password-Policy_DE.png\" alt=\"Bucket-basierte Passwortrichtlinien in der Cortado MDM Admin Portal\" class=\"wp-image-9381\" srcset=\"https:\/\/www.cortado.com\/wp-content\/uploads\/Bucket-Based-Password-Policy_DE.png 874w, https:\/\/www.cortado.com\/wp-content\/uploads\/Bucket-Based-Password-Policy_DE-300x226.png 300w, https:\/\/www.cortado.com\/wp-content\/uploads\/Bucket-Based-Password-Policy_DE-768x578.png 768w\" sizes=\"auto, (max-width: 874px) 100vw, 874px\" \/><figcaption class=\"wp-element-caption\">Bucket-basierte Passwortrichtlinien in der Cortado MDM Admin Portal<\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"h-einfuhrung-der-bucket-basierten-passwortrichtlinie\">Einf\u00fchrung der Bucket-basierten Passwortrichtlinie<\/h2>\n\n\n\n<p>Mit der Einf\u00fchrung der neuen Bucket-basierten Sicherheitsrichtlinie folgen wir den aktuellen Empfehlungen von Google zur Verbesserung der Sicherheit des Ger\u00e4tezugangs. Wir empfehlen, alle Ihre Richtlinien auf das neue Sicherheitsmodell zu aktualisieren, da benutzerdefinierte Passwortrichtlinien in neueren Android-Versionen nicht mehr verwendet werden. Lesen Sie mehr in unserem Blogbeitrag: \u201e<a href=\"https:\/\/blog.cortado.com\/de\/passwoerter-android-12\/\">Wie \u00e4ndern sich Passw\u00f6rter in Android 12?<\/a>\u201c.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-neue-android-richtlinien\">Neue Android-Richtlinien<\/h2>\n\n\n\n<p>Zus\u00e4tzlich zu den Verbesserungen bei der Kennwortrichtlinie haben wir weitere neue Richtlinieneinstellungen f\u00fcr vollst\u00e4ndig verwaltete Android-Ger\u00e4te hinzugef\u00fcgt. Dazu geh\u00f6ren: Flugmodus zulassen, mehrfache Lautst\u00e4rkeeinstellungen, Common Criteria-Modus, Verwendung von Bluetooth zulassen und Freigabe \u00fcber Bluetooth. Weitere Einstellungen werden mit unseren n\u00e4chsten Updates verf\u00fcgbar sein.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ab-sofort-in-cortado-mdm-verfugbar-auch-mit-kostenloser-testphase\">Ab sofort in Cortado MDM verf\u00fcgbar \u2013 auch mit kostenloser Testphase<\/h2>\n\n\n\n<p>Sie nutzen Cortado MDM noch nicht? Hier finden Sie weitere Informationen und k\u00f6nnen sich f\u00fcr einen kostenlosen Test registrieren:&nbsp;<a href=\"https:\/\/www.cortado.com\/de\/testen\/\">Kostenlos testen \u2013 Cortado MDM<\/a><\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-image-fill  has-background\" style=\"background-color:#5d9200;\"><figure class=\"wp-block-media-text__media\" style=\"background-image:url(https:\/\/www.cortado.com\/wp-content\/uploads\/\/private-phones-company-1024x576.jpg);background-position:36% 59%\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.cortado.com\/wp-content\/uploads\/\/private-phones-company-1024x576.jpg\" alt=\"Woman working at home with laptop and smartphone.\" class=\"wp-image-10308 size-full\" srcset=\"https:\/\/www.cortado.com\/wp-content\/uploads\/private-phones-company-1024x576.jpg 1024w, https:\/\/www.cortado.com\/wp-content\/uploads\/private-phones-company-300x169.jpg 300w, https:\/\/www.cortado.com\/wp-content\/uploads\/private-phones-company-768x432.jpg 768w, https:\/\/www.cortado.com\/wp-content\/uploads\/private-phones-company.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-color has-link-color has-large-font-size wp-elements-753f3caaf30b19624a5558dbe7a4f757\" style=\"color:#ffffff\">Noch kein Cortado-Kunde?<\/p>\n\n\n\n<p class=\"has-text-color has-link-color has-medium-font-size wp-elements-b23acf186994b7215a9c70ace1534fe6\" style=\"color:#ffffff\">Testen Sie Cortado MDM kostenlos und unverbindlich!<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-text-color has-link-color wp-element-button\" href=\"\/de\/testen\/\" style=\"color:#ffffff\">Jetzt kostenlos testen<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Neu in Cortado MDM \u2013 Verbesserte Kennwortrichtlinien f\u00fcr Android 12-Ger\u00e4te. Lesen Sie mehr \u00fcber das Update in diesem Post.<\/p>\n","protected":false},"author":17,"featured_media":10358,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1,10968],"tags":[],"class_list":["post-10042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-produktupdates"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.9 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Verbesserte Kennwortrichtlinien (Android 12) \u2013 Cortado MDM<\/title>\n<meta name=\"description\" content=\"Neu in Cortado MDM \u2013 Verbesserte Kennwortrichtlinien f\u00fcr Android 12-Ger\u00e4te. Lesen Sie mehr \u00fcber das Update in diesem Post.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cortado.com\/de\/news\/verbesserte-kennwortrichtlinien-android\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verbesserte Kennwortrichtlinien f\u00fcr Android-Ger\u00e4te\" \/>\n<meta property=\"og:description\" content=\"Neu in Cortado MDM \u2013 Verbesserte Kennwortrichtlinien f\u00fcr Android 12-Ger\u00e4te. Lesen Sie mehr \u00fcber das Update in diesem Post.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cortado.com\/de\/news\/verbesserte-kennwortrichtlinien-android\/\" \/>\n<meta property=\"og:site_name\" content=\"Cortado\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CortadoMobileSolutions\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-02T15:40:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-10T09:41:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cortado.com\/wp-content\/uploads\/Bucket-Based-Password-Policy_DE.png\" \/>\n\t<meta property=\"og:image:width\" content=\"874\" \/>\n\t<meta property=\"og:image:height\" content=\"658\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Dana Meier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cortado_com\" \/>\n<meta name=\"twitter:site\" content=\"@cortado_com\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dana Meier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/verbesserte-kennwortrichtlinien-android\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/verbesserte-kennwortrichtlinien-android\\\/\"},\"author\":{\"name\":\"Dana Meier\",\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/#\\\/schema\\\/person\\\/ac9f1fc506c87ac46dfd6afa638329cc\"},\"headline\":\"Verbesserte Kennwortrichtlinien f\u00fcr Android-Ger\u00e4te\",\"datePublished\":\"2021-12-02T15:40:12+00:00\",\"dateModified\":\"2025-01-10T09:41:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/verbesserte-kennwortrichtlinien-android\\\/\"},\"wordCount\":165,\"image\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/verbesserte-kennwortrichtlinien-android\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cortado.com\\\/wp-content\\\/uploads\\\/Neu-in-Cortado-MDM-Label-1.png\",\"articleSection\":[\"Alle News &amp; Updates\",\"Produkt-Updates\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/verbesserte-kennwortrichtlinien-android\\\/\",\"url\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/verbesserte-kennwortrichtlinien-android\\\/\",\"name\":\"Verbesserte Kennwortrichtlinien (Android 12) \u2013 Cortado MDM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/verbesserte-kennwortrichtlinien-android\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/verbesserte-kennwortrichtlinien-android\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cortado.com\\\/wp-content\\\/uploads\\\/Neu-in-Cortado-MDM-Label-1.png\",\"datePublished\":\"2021-12-02T15:40:12+00:00\",\"dateModified\":\"2025-01-10T09:41:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/#\\\/schema\\\/person\\\/ac9f1fc506c87ac46dfd6afa638329cc\"},\"description\":\"Neu in Cortado MDM \u2013 Verbesserte Kennwortrichtlinien f\u00fcr Android 12-Ger\u00e4te. Lesen Sie mehr \u00fcber das Update in diesem Post.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/verbesserte-kennwortrichtlinien-android\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/verbesserte-kennwortrichtlinien-android\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/verbesserte-kennwortrichtlinien-android\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cortado.com\\\/wp-content\\\/uploads\\\/Neu-in-Cortado-MDM-Label-1.png\",\"contentUrl\":\"https:\\\/\\\/www.cortado.com\\\/wp-content\\\/uploads\\\/Neu-in-Cortado-MDM-Label-1.png\",\"width\":720,\"height\":720,\"caption\":\"Neu in Cortado MDM (Label)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/verbesserte-kennwortrichtlinien-android\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verbesserte Kennwortrichtlinien f\u00fcr Android-Ger\u00e4te\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/\",\"name\":\"Cortado\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/#\\\/schema\\\/person\\\/ac9f1fc506c87ac46dfd6afa638329cc\",\"name\":\"Dana Meier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf3fd2e38bc822d322ecef24a517664752aa89f970bd31ab1a80c9a5f4117357?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf3fd2e38bc822d322ecef24a517664752aa89f970bd31ab1a80c9a5f4117357?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf3fd2e38bc822d322ecef24a517664752aa89f970bd31ab1a80c9a5f4117357?s=96&d=mm&r=g\",\"caption\":\"Dana Meier\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Verbesserte Kennwortrichtlinien (Android 12) \u2013 Cortado MDM","description":"Neu in Cortado MDM \u2013 Verbesserte Kennwortrichtlinien f\u00fcr Android 12-Ger\u00e4te. Lesen Sie mehr \u00fcber das Update in diesem Post.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cortado.com\/de\/news\/verbesserte-kennwortrichtlinien-android\/","og_locale":"de_DE","og_type":"article","og_title":"Verbesserte Kennwortrichtlinien f\u00fcr Android-Ger\u00e4te","og_description":"Neu in Cortado MDM \u2013 Verbesserte Kennwortrichtlinien f\u00fcr Android 12-Ger\u00e4te. Lesen Sie mehr \u00fcber das Update in diesem Post.","og_url":"https:\/\/www.cortado.com\/de\/news\/verbesserte-kennwortrichtlinien-android\/","og_site_name":"Cortado","article_publisher":"https:\/\/www.facebook.com\/CortadoMobileSolutions\/","article_published_time":"2021-12-02T15:40:12+00:00","article_modified_time":"2025-01-10T09:41:06+00:00","og_image":[{"width":874,"height":658,"url":"https:\/\/www.cortado.com\/wp-content\/uploads\/Bucket-Based-Password-Policy_DE.png","type":"image\/png"}],"author":"Dana Meier","twitter_card":"summary_large_image","twitter_creator":"@cortado_com","twitter_site":"@cortado_com","twitter_misc":{"Verfasst von":"Dana Meier","Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cortado.com\/de\/news\/verbesserte-kennwortrichtlinien-android\/#article","isPartOf":{"@id":"https:\/\/www.cortado.com\/de\/news\/verbesserte-kennwortrichtlinien-android\/"},"author":{"name":"Dana Meier","@id":"https:\/\/www.cortado.com\/de\/#\/schema\/person\/ac9f1fc506c87ac46dfd6afa638329cc"},"headline":"Verbesserte Kennwortrichtlinien f\u00fcr Android-Ger\u00e4te","datePublished":"2021-12-02T15:40:12+00:00","dateModified":"2025-01-10T09:41:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cortado.com\/de\/news\/verbesserte-kennwortrichtlinien-android\/"},"wordCount":165,"image":{"@id":"https:\/\/www.cortado.com\/de\/news\/verbesserte-kennwortrichtlinien-android\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cortado.com\/wp-content\/uploads\/Neu-in-Cortado-MDM-Label-1.png","articleSection":["Alle News &amp; Updates","Produkt-Updates"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.cortado.com\/de\/news\/verbesserte-kennwortrichtlinien-android\/","url":"https:\/\/www.cortado.com\/de\/news\/verbesserte-kennwortrichtlinien-android\/","name":"Verbesserte Kennwortrichtlinien (Android 12) \u2013 Cortado MDM","isPartOf":{"@id":"https:\/\/www.cortado.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cortado.com\/de\/news\/verbesserte-kennwortrichtlinien-android\/#primaryimage"},"image":{"@id":"https:\/\/www.cortado.com\/de\/news\/verbesserte-kennwortrichtlinien-android\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cortado.com\/wp-content\/uploads\/Neu-in-Cortado-MDM-Label-1.png","datePublished":"2021-12-02T15:40:12+00:00","dateModified":"2025-01-10T09:41:06+00:00","author":{"@id":"https:\/\/www.cortado.com\/de\/#\/schema\/person\/ac9f1fc506c87ac46dfd6afa638329cc"},"description":"Neu in Cortado MDM \u2013 Verbesserte Kennwortrichtlinien f\u00fcr Android 12-Ger\u00e4te. Lesen Sie mehr \u00fcber das Update in diesem Post.","breadcrumb":{"@id":"https:\/\/www.cortado.com\/de\/news\/verbesserte-kennwortrichtlinien-android\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cortado.com\/de\/news\/verbesserte-kennwortrichtlinien-android\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.cortado.com\/de\/news\/verbesserte-kennwortrichtlinien-android\/#primaryimage","url":"https:\/\/www.cortado.com\/wp-content\/uploads\/Neu-in-Cortado-MDM-Label-1.png","contentUrl":"https:\/\/www.cortado.com\/wp-content\/uploads\/Neu-in-Cortado-MDM-Label-1.png","width":720,"height":720,"caption":"Neu in Cortado MDM (Label)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cortado.com\/de\/news\/verbesserte-kennwortrichtlinien-android\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cortado.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Verbesserte Kennwortrichtlinien f\u00fcr Android-Ger\u00e4te"}]},{"@type":"WebSite","@id":"https:\/\/www.cortado.com\/de\/#website","url":"https:\/\/www.cortado.com\/de\/","name":"Cortado","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cortado.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/www.cortado.com\/de\/#\/schema\/person\/ac9f1fc506c87ac46dfd6afa638329cc","name":"Dana Meier","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/cf3fd2e38bc822d322ecef24a517664752aa89f970bd31ab1a80c9a5f4117357?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cf3fd2e38bc822d322ecef24a517664752aa89f970bd31ab1a80c9a5f4117357?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf3fd2e38bc822d322ecef24a517664752aa89f970bd31ab1a80c9a5f4117357?s=96&d=mm&r=g","caption":"Dana Meier"}}]}},"author_meta":{"display_name":"Dana Meier","author_link":"https:\/\/www.cortado.com\/de\/author\/damei\/"},"featured_img":"https:\/\/www.cortado.com\/wp-content\/uploads\/Neu-in-Cortado-MDM-Label-1-300x300.png","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.cortado.com\/de\/kategorie\/news\/\" class=\"advgb-post-tax-term\">Alle News &amp; Updates<\/a>","<a href=\"https:\/\/www.cortado.com\/de\/kategorie\/produktupdates\/\" class=\"advgb-post-tax-term\">Produkt-Updates<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Alle News &amp; Updates<\/span>","<span class=\"advgb-post-tax-term\">Produkt-Updates<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Ver\u00f6ffentlicht 5 Jahren vor","modified":"Aktualisiert 2 Jahren vor"},"absolute_dates":{"created":"Ver\u00f6ffentlicht am Dezember 2, 2021","modified":"Aktualisiert am Januar 10, 2025"},"absolute_dates_time":{"created":"Ver\u00f6ffentlicht am Dezember 2, 2021 3:40 pm","modified":"Aktualisiert am Januar 10, 2025 9:41 am"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/posts\/10042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/comments?post=10042"}],"version-history":[{"count":0,"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/posts\/10042\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/media\/10358"}],"wp:attachment":[{"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/media?parent=10042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/categories?post=10042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/tags?post=10042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}