{"id":14631,"date":"2025-02-04T14:25:08","date_gmt":"2025-02-04T14:25:08","guid":{"rendered":"https:\/\/www.cortado.com\/?p=14631"},"modified":"2025-02-04T14:25:09","modified_gmt":"2025-02-04T14:25:09","slug":"cortado-mitglied-im-bundesverband-it-mittelstand","status":"publish","type":"post","link":"https:\/\/www.cortado.com\/de\/news\/cortado-mitglied-im-bundesverband-it-mittelstand\/","title":{"rendered":"Cortado Mobile Solutions ist ab sofort Mitglied im Bundesverband IT-Mittelstand e.V. (BITMi)"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Seit dem 1. Februar 2025 ist Cortado Mobile Solutions offizielles Mitglied im Bundesverband IT-Mittelstand e.V. (BITMi). Mit dieser Mitgliedschaft st\u00e4rkt das Unternehmen seine Position als f\u00fchrender Anbieter von Mobile Device Management (MDM)-L\u00f6sungen und unterstreicht sein Engagement f\u00fcr die F\u00f6rderung innovativer IT-L\u00f6sungen im Mittelstand.<\/p>\n\n\n\n<p>Der BITMi vertritt als einziger IT-Fachverband ausschlie\u00dflich mittelst\u00e4ndische Unternehmen der deutschen IT-Wirtschaft und setzt sich aktiv f\u00fcr deren Interessen ein. Durch den Austausch mit anderen IT-Unternehmen und die Mitgestaltung politischer Rahmenbedingungen kann Cortado Mobile Solutions noch gezielter auf die Bed\u00fcrfnisse von KMUs eingehen und seine L\u00f6sungen weiter optimieren.<\/p>\n\n\n\n<p>Mit <a href=\"https:\/\/www.cortado.com\/de\/produkt\/#devices\">Cortado MDM<\/a> bietet das Unternehmen eine einfache, sichere und DSGVO-konforme Verwaltung von mobilen Ger\u00e4ten f\u00fcr Unternehmen jeder Gr\u00f6\u00dfe \u2013 von kleinen Betrieben bis hin zu gro\u00dfen Organisationen. Die Mitgliedschaft im BITMi er\u00f6ffnet neue M\u00f6glichkeiten zur Vernetzung, Zusammenarbeit und Einflussnahme auf die digitale Zukunft des Mittelstands.<\/p>\n\n\n\n<p>\u201eDie BITMi-Mitgliedschaft erm\u00f6glicht es uns, die Digitalisierung mittelst\u00e4ndischer Unternehmen aktiv mitzugestalten und unsere Expertise im Bereich Mobile Device Management gezielt einzubringen. Wir freuen uns auf den Austausch und die Zusammenarbeit!\u201c \u2013 Michael R\u00f6diger, Gesch\u00e4ftsf\u00fchrer Cortado Mobile Solution<\/p>\n\n\n\n<p>Mehr \u00fcber den BITMi: <a href=\"http:\/\/www.bitmi.de\" target=\"_blank\" rel=\"noreferrer noopener\">www.bitmi.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seit 1. Februar 2025 ist Cortado Mitglied im Bundesverband IT-Mittelstand e.V.<\/p>\n","protected":false},"author":8,"featured_media":14633,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1,7,10969],"tags":[],"class_list":{"0":"post-14631","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-news","9":"category-unternehmensnews"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.9 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cortado ist Mitglied im Bundesverband IT-Mittelstand<\/title>\n<meta name=\"description\" content=\"Seit 1. Februar 2025 ist Cortado Mitglied im Bundesverband IT-Mittelstand e.V.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cortado.com\/de\/news\/cortado-mitglied-im-bundesverband-it-mittelstand\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cortado Mobile Solutions ist ab sofort Mitglied im Bundesverband IT-Mittelstand e.V. (BITMi)\" \/>\n<meta property=\"og:description\" content=\"Seit 1. Februar 2025 ist Cortado Mitglied im Bundesverband IT-Mittelstand e.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cortado.com\/de\/news\/cortado-mitglied-im-bundesverband-it-mittelstand\/\" \/>\n<meta property=\"og:site_name\" content=\"Cortado\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CortadoMobileSolutions\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-04T14:25:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-04T14:25:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cortado.com\/wp-content\/uploads\/Mitglied-im-BITMi-Logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1163\" \/>\n\t<meta property=\"og:image:height\" content=\"949\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Simone Fulton\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cortado_com\" \/>\n<meta name=\"twitter:site\" content=\"@cortado_com\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Simone Fulton\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/cortado-mitglied-im-bundesverband-it-mittelstand\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/cortado-mitglied-im-bundesverband-it-mittelstand\\\/\"},\"author\":{\"name\":\"Simone Fulton\",\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/#\\\/schema\\\/person\\\/a208d5b9f4830dc26b3fc3b59dd909ea\"},\"headline\":\"Cortado Mobile Solutions ist ab sofort Mitglied im Bundesverband IT-Mittelstand e.V. (BITMi)\",\"datePublished\":\"2025-02-04T14:25:08+00:00\",\"dateModified\":\"2025-02-04T14:25:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/cortado-mitglied-im-bundesverband-it-mittelstand\\\/\"},\"wordCount\":214,\"image\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/cortado-mitglied-im-bundesverband-it-mittelstand\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cortado.com\\\/wp-content\\\/uploads\\\/Mitglied-im-BITMi-Logo.jpg\",\"articleSection\":[\"Alle News &amp; Updates\",\"News\",\"Unternehmens-News\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/cortado-mitglied-im-bundesverband-it-mittelstand\\\/\",\"url\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/cortado-mitglied-im-bundesverband-it-mittelstand\\\/\",\"name\":\"Cortado ist Mitglied im Bundesverband IT-Mittelstand\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/cortado-mitglied-im-bundesverband-it-mittelstand\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/cortado-mitglied-im-bundesverband-it-mittelstand\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cortado.com\\\/wp-content\\\/uploads\\\/Mitglied-im-BITMi-Logo.jpg\",\"datePublished\":\"2025-02-04T14:25:08+00:00\",\"dateModified\":\"2025-02-04T14:25:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/#\\\/schema\\\/person\\\/a208d5b9f4830dc26b3fc3b59dd909ea\"},\"description\":\"Seit 1. Februar 2025 ist Cortado Mitglied im Bundesverband IT-Mittelstand e.V.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/cortado-mitglied-im-bundesverband-it-mittelstand\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/cortado-mitglied-im-bundesverband-it-mittelstand\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/cortado-mitglied-im-bundesverband-it-mittelstand\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cortado.com\\\/wp-content\\\/uploads\\\/Mitglied-im-BITMi-Logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cortado.com\\\/wp-content\\\/uploads\\\/Mitglied-im-BITMi-Logo.jpg\",\"width\":1163,\"height\":949,\"caption\":\"Mitglied im bitmi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/news\\\/cortado-mitglied-im-bundesverband-it-mittelstand\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cortado Mobile Solutions ist ab sofort Mitglied im Bundesverband IT-Mittelstand e.V. (BITMi)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/\",\"name\":\"Cortado\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cortado.com\\\/de\\\/#\\\/schema\\\/person\\\/a208d5b9f4830dc26b3fc3b59dd909ea\",\"name\":\"Simone Fulton\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/40636cdacf48abcbccbdd0b19f88fbab69252a38f765fb1d02b033d491a6f98f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/40636cdacf48abcbccbdd0b19f88fbab69252a38f765fb1d02b033d491a6f98f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/40636cdacf48abcbccbdd0b19f88fbab69252a38f765fb1d02b033d491a6f98f?s=96&d=mm&r=g\",\"caption\":\"Simone Fulton\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cortado ist Mitglied im Bundesverband IT-Mittelstand","description":"Seit 1. Februar 2025 ist Cortado Mitglied im Bundesverband IT-Mittelstand e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cortado.com\/de\/news\/cortado-mitglied-im-bundesverband-it-mittelstand\/","og_locale":"de_DE","og_type":"article","og_title":"Cortado Mobile Solutions ist ab sofort Mitglied im Bundesverband IT-Mittelstand e.V. (BITMi)","og_description":"Seit 1. Februar 2025 ist Cortado Mitglied im Bundesverband IT-Mittelstand e.V.","og_url":"https:\/\/www.cortado.com\/de\/news\/cortado-mitglied-im-bundesverband-it-mittelstand\/","og_site_name":"Cortado","article_publisher":"https:\/\/www.facebook.com\/CortadoMobileSolutions\/","article_published_time":"2025-02-04T14:25:08+00:00","article_modified_time":"2025-02-04T14:25:09+00:00","og_image":[{"width":1163,"height":949,"url":"https:\/\/www.cortado.com\/wp-content\/uploads\/Mitglied-im-BITMi-Logo.jpg","type":"image\/jpeg"}],"author":"Simone Fulton","twitter_card":"summary_large_image","twitter_creator":"@cortado_com","twitter_site":"@cortado_com","twitter_misc":{"Verfasst von":"Simone Fulton","Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cortado.com\/de\/news\/cortado-mitglied-im-bundesverband-it-mittelstand\/#article","isPartOf":{"@id":"https:\/\/www.cortado.com\/de\/news\/cortado-mitglied-im-bundesverband-it-mittelstand\/"},"author":{"name":"Simone Fulton","@id":"https:\/\/www.cortado.com\/de\/#\/schema\/person\/a208d5b9f4830dc26b3fc3b59dd909ea"},"headline":"Cortado Mobile Solutions ist ab sofort Mitglied im Bundesverband IT-Mittelstand e.V. (BITMi)","datePublished":"2025-02-04T14:25:08+00:00","dateModified":"2025-02-04T14:25:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cortado.com\/de\/news\/cortado-mitglied-im-bundesverband-it-mittelstand\/"},"wordCount":214,"image":{"@id":"https:\/\/www.cortado.com\/de\/news\/cortado-mitglied-im-bundesverband-it-mittelstand\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cortado.com\/wp-content\/uploads\/Mitglied-im-BITMi-Logo.jpg","articleSection":["Alle News &amp; Updates","News","Unternehmens-News"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.cortado.com\/de\/news\/cortado-mitglied-im-bundesverband-it-mittelstand\/","url":"https:\/\/www.cortado.com\/de\/news\/cortado-mitglied-im-bundesverband-it-mittelstand\/","name":"Cortado ist Mitglied im Bundesverband IT-Mittelstand","isPartOf":{"@id":"https:\/\/www.cortado.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cortado.com\/de\/news\/cortado-mitglied-im-bundesverband-it-mittelstand\/#primaryimage"},"image":{"@id":"https:\/\/www.cortado.com\/de\/news\/cortado-mitglied-im-bundesverband-it-mittelstand\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cortado.com\/wp-content\/uploads\/Mitglied-im-BITMi-Logo.jpg","datePublished":"2025-02-04T14:25:08+00:00","dateModified":"2025-02-04T14:25:09+00:00","author":{"@id":"https:\/\/www.cortado.com\/de\/#\/schema\/person\/a208d5b9f4830dc26b3fc3b59dd909ea"},"description":"Seit 1. Februar 2025 ist Cortado Mitglied im Bundesverband IT-Mittelstand e.V.","breadcrumb":{"@id":"https:\/\/www.cortado.com\/de\/news\/cortado-mitglied-im-bundesverband-it-mittelstand\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cortado.com\/de\/news\/cortado-mitglied-im-bundesverband-it-mittelstand\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.cortado.com\/de\/news\/cortado-mitglied-im-bundesverband-it-mittelstand\/#primaryimage","url":"https:\/\/www.cortado.com\/wp-content\/uploads\/Mitglied-im-BITMi-Logo.jpg","contentUrl":"https:\/\/www.cortado.com\/wp-content\/uploads\/Mitglied-im-BITMi-Logo.jpg","width":1163,"height":949,"caption":"Mitglied im bitmi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cortado.com\/de\/news\/cortado-mitglied-im-bundesverband-it-mittelstand\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cortado.com\/de\/"},{"@type":"ListItem","position":2,"name":"Cortado Mobile Solutions ist ab sofort Mitglied im Bundesverband IT-Mittelstand e.V. (BITMi)"}]},{"@type":"WebSite","@id":"https:\/\/www.cortado.com\/de\/#website","url":"https:\/\/www.cortado.com\/de\/","name":"Cortado","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cortado.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/www.cortado.com\/de\/#\/schema\/person\/a208d5b9f4830dc26b3fc3b59dd909ea","name":"Simone Fulton","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/40636cdacf48abcbccbdd0b19f88fbab69252a38f765fb1d02b033d491a6f98f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/40636cdacf48abcbccbdd0b19f88fbab69252a38f765fb1d02b033d491a6f98f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/40636cdacf48abcbccbdd0b19f88fbab69252a38f765fb1d02b033d491a6f98f?s=96&d=mm&r=g","caption":"Simone Fulton"}}]}},"author_meta":{"display_name":"Simone Fulton","author_link":"https:\/\/www.cortado.com\/de\/author\/siklu\/"},"featured_img":"https:\/\/www.cortado.com\/wp-content\/uploads\/Mitglied-im-BITMi-Logo-300x245.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.cortado.com\/de\/kategorie\/news\/\" class=\"advgb-post-tax-term\">Alle News &amp; Updates<\/a>","<a href=\"https:\/\/www.cortado.com\/en\/cat\/news\/\" class=\"advgb-post-tax-term\">News<\/a>","<a href=\"https:\/\/www.cortado.com\/de\/kategorie\/unternehmensnews\/\" class=\"advgb-post-tax-term\">Unternehmens-News<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Alle News &amp; Updates<\/span>","<span class=\"advgb-post-tax-term\">News<\/span>","<span class=\"advgb-post-tax-term\">Unternehmens-News<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Ver\u00f6ffentlicht 1 Jahr vor","modified":"Aktualisiert 1 Jahr vor"},"absolute_dates":{"created":"Ver\u00f6ffentlicht am Februar 4, 2025","modified":"Aktualisiert am Februar 4, 2025"},"absolute_dates_time":{"created":"Ver\u00f6ffentlicht am Februar 4, 2025 2:25 pm","modified":"Aktualisiert am Februar 4, 2025 2:25 pm"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/posts\/14631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/comments?post=14631"}],"version-history":[{"count":0,"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/posts\/14631\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/media\/14633"}],"wp:attachment":[{"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/media?parent=14631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/categories?post=14631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cortado.com\/de\/wp-json\/wp\/v2\/tags?post=14631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}